{"id":23028,"date":"2026-09-01T10:30:28","date_gmt":"2026-09-01T08:30:28","guid":{"rendered":"https:\/\/esportsinsider.com\/de\/?p=23028"},"modified":"2026-09-01T10:30:29","modified_gmt":"2026-09-01T08:30:29","slug":"esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg","status":"publish","type":"post","link":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg","title":{"rendered":"Esports World Cup sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM bleiben gr\u00f6\u00dfte Veranstaltungen"},"content":{"rendered":"<div id=\"esi-paragraph-6a98a74223bbe\" class=\"esi-paragraph \">\n    \n<p>In der letzten Woche der Esport-Weltmeisterschaft wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten sieben Tagen des Turniers wurden bei Esport-Veranstaltungen insgesamt \u00fcber 95 Mio. $ umgesetzt.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a74223cc6\" class=\"esi-paragraph \">\n    \n<p>Dies war ein Anstieg gegen\u00fcber den 90 Mio. $ der Vorwoche. Mit einer Ausnahme lag das Handelsvolumen in jeder Woche des Turniers \u00fcber 70 Mio. $, wobei nicht alle Handelsgesch\u00e4fte auf die Weltmeisterschaft entfielen.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a74223d97\" class=\"esi-paragraph \">\n    \n<p>Tats\u00e4chlich wurde letzte Woche bei \u201eLeague of Legends\u201c-Events genauso viel gehandelt wie bei \u201eCounter-Strike 2\u201c, obwohl Letzteres bei der Weltmeisterschaft im Rampenlicht stand. Bei beiden Spielen belief sich das Gesamtvolumen auf rund 32 Mio. $.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-heading-6a98a74223f51\" class=\"esi-heading \">\n  \n<h2 class=\"wp-block-heading\">IEM K\u00f6ln f\u00fchrt den Esports World Cup beim CS2-Handelsvolumen an<\/h2>\n\n<\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422401c\" class=\"esi-paragraph \">\n    \n<p>Das Viertelfinalspiel zwischen Spirit und Vitality war das am meisten gehandelte CS2-Spiel beim Esports World Cup. Das Handelsvolumen \u00fcberschritt \u00fcber alle M\u00e4rkte hinweg die 3-32 Mio.-$-Marke. Damit lag es knapp \u00fcber dem Finale zwischen Spirit und FUT Esports, das 2,9 32 Mio. $ einbrachte.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a742240f4\" class=\"esi-paragraph \">\n    \n<p>Obwohl letzte Woche der Rekord f\u00fcr das h\u00f6chste w\u00f6chentliche Esport-Handelsvolumen aller Zeiten auf Kalshi gebrochen wurde, bleibt die IEM K\u00f6ln das am meisten gehandelte CS2-Event. Im Laufe des Turniers wurden \u00fcber 109 32 Mio. $ umgesetzt.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a742241b6\" class=\"esi-paragraph \">\n    \n<p>Das Spiel von Spirit gegen Team Falcons bei der IEM bleibt das am meisten gehandelte Spiel, mit einem Handelsvolumen von \u00fcber 4,5 32 Mio. $ \u00fcber alle M\u00e4rkte hinweg.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422427a\" class=\"esi-paragraph \">\n    \n<p>Betrachtet man die gr\u00f6\u00dften M\u00e4rkte f\u00fcr den Match-Sieger, so dominiert die IEM K\u00f6ln laut Daten von TickerTracker die Top 10 mit acht der Spiele.<\/p>\n\n  <\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"988\" height=\"730\" src=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-numbers.png.webp\" alt=\"EWC-Zahlen\" class=\"wp-image-23030\" srcset=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-numbers.png.webp 988w, https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-numbers.png-medium.webp 300w, https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-numbers.png-medium_large.webp 768w\" sizes=\"(max-width: 988px) 100vw, 988px\" \/><figcaption class=\"wp-element-caption\">Image Credit: TicketTracker<\/figcaption><\/figure>\n<\/div>\n\n<div id=\"esi-heading-6a98a742259a7\" class=\"esi-heading \">\n  \n<h2 class=\"wp-block-heading\">\u201eLeague of Legends\u201c ist nun das mit Abstand meistgehandelte Spiel<\/h2>\n\n<\/div>\n\n\n<div id=\"esi-paragraph-6a98a74225aaf\" class=\"esi-paragraph \">\n    \n<p>Als die IEM Cologne stattfand, dominierte CS2 die E-Sport-Kategorie von Kalshi und machte rund 65 % des gesamten Handelsvolumens aus. Inzwischen wurde es von \u201eLeague of Legends\u201c \u00fcberholt.<\/p>\n\n  <\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter\"><img decoding=\"async\" width=\"747\" height=\"469\" src=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/unnamed-3.png.webp\" alt=\"28-Tagesdurchschnitt\" class=\"wp-image-23031\" srcset=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/unnamed-3.png.webp 747w, https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/unnamed-3.png-medium.webp 300w\" sizes=\"(max-width: 747px) 100vw, 747px\" \/><\/figure>\n<\/div>\n\n<div id=\"esi-paragraph-6a98a74225c42\" class=\"esi-paragraph \">\n    \n<p>In den letzten 28 Tagen lag das durchschnittliche Tagesvolumen bei \u201eLeague of Legends\u201c bei fast 5 Mio. $, ein Anstieg gegen\u00fcber rund 2 Mio. $ im gleichen Zeitraum des Vormonats. Bei \u201eCS2\u201c wurde im Juni ein H\u00f6chststand von 4,6 Mio. $ erreicht, der w\u00e4hrend der Weltmeisterschaft in der vergangenen Woche erneut auf rund 4 Mio. $ anstieg.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a74225d13\" class=\"esi-paragraph \">\n    \n<p>Das MSI bleibt das am meisten gehandelte LoL-Event. Das Spiel Lyon gegen Hanwha Sports war mit einem Umsatz von 5,9 Mio. $ das am meisten gehandelte Spiel aller Veranstaltungen.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a74225dda\" class=\"esi-paragraph \">\n    \n<p>Betrachtet man die M\u00e4rkte f\u00fcr den Sieg eines Spiels, die die h\u00f6chsten Ums\u00e4tze verzeichnen, so fanden alle 10 Top-M\u00e4rkte bei LoL im Rahmen des MSI statt.<\/p>\n\n  <\/div>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" width=\"985\" height=\"720\" src=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-nubmers-2.png.webp\" alt=\"EWC-Zahlen 2\" class=\"wp-image-23032\" srcset=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-nubmers-2.png.webp 985w, https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-nubmers-2.png-medium.webp 300w, https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/ewc-nubmers-2.png-medium_large.webp 768w\" sizes=\"(max-width: 985px) 100vw, 985px\" \/><figcaption class=\"wp-element-caption\">Image Credit: TicketTracker<\/figcaption><\/figure>\n\n\n<div id=\"esi-heading-6a98a74225f30\" class=\"esi-heading \">\n  \n<h2 class=\"wp-block-heading\">Esport-Handelsvolumen bei Kalshi und Polymarket \u00fcbersteigt 1 Mrd. $<\/h2>\n\n<\/div>\n\n\n<div id=\"esi-paragraph-6a98a74226012\" class=\"esi-paragraph \">\n    \n<p>Seit Jahresbeginn wurden bei Kalshi \u00fcber 1,3 Mrd. $ im Esport-Bereich umgesetzt, wobei \u201eLeague of Legends\u201c und \u201eCS2\u201c rund 85 % davon ausmachten.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a742260d7\" class=\"esi-paragraph \">\n    \n<p>Auch bei Polymarket verzeichnet \u201eLeague of Legends\u201c h\u00f6here Handelsvolumina: Die durchschnittlichen Ums\u00e4tze pro Spiel liegen bei 1,2 Mio. $, w\u00e4hrend sie bei \u201eCS2\u201c knapp unter 1 Mio. $ betragen.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422619a\" class=\"esi-paragraph \">\n    \n<p>Diese Zahlen liegen nicht weit hinter denen der gro\u00dfen Profisportligen zur\u00fcck: Bei NHL-Spielen liegt das durchschnittliche Handelsvolumen bei 3 Mio. $. Bei der NBA und der MLB liegen die Werte bei rund 4 Mio. $ pro Spiel, wobei die NFL mit \u00fcber 5 Mio. $ an der Spitze liegt. Angesichts des Aufschwungs der Prognosem\u00e4rkte seit dem Super Bowl wird erwartet, dass die neue NFL-Saison sowohl bei Polymarket als auch bei Kalshi weitaus h\u00f6here Handelsvolumina anziehen wird.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422625b\" class=\"esi-paragraph \">\n    \n<p>Es sollte sicherlich beachtet werden, dass das Handelsvolumen nicht mit dem Umsatz bei Sportwetten gleichzusetzen ist. Der Umsatz bei Sportwetten erfasst lediglich den von den Spielern eingesetzten Betrag, w\u00e4hrend das Handelsvolumen sowohl das auf einer Seite eingesetzte Geld als auch die potenzielle Auszahlung auf der anderen Seite umfasst.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422631d\" class=\"esi-paragraph \">\n    \n<p>Dennoch zeigen die steigenden Zahlen, dass immer mehr Nutzer zu den Esport-Prognosem\u00e4rkten str\u00f6men.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-heading-6a98a74226408\" class=\"esi-heading \">\n  \n<h2 class=\"wp-block-heading\">Rechtliche Entwicklungen bei Esport-Wetten in dieser Woche<\/h2>\n\n<\/div>\n\n\n<div id=\"esi-paragraph-6a98a742264d0\" class=\"esi-paragraph \">\n    \n<p>Wie immer gab es auch in dieser Woche mehrere Entwicklungen in den Rechtsstreitigkeiten zwischen Bundesstaaten und Prognosem\u00e4rkten. Am bemerkenswertesten ist vielleicht der Fall Connecticut, das eine neue Klage gegen Kalshi eingereicht hat, um die Sportwetten der Plattform zu unterbinden.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422658f\" class=\"esi-paragraph \">\n    \n<p>Ein Richter in Connecticut hat bereits entschieden, dass es sich bei den M\u00e4rkten von Kalshi um Sportwetten handelt, doch Kalshi legte beim Zweiten Bundesberufungsgericht Berufung ein. W\u00e4hrend dieses Berufungsverfahren noch l\u00e4uft, beantragt der Bundesstaat eine Verf\u00fcgung, die die Sportwettenm\u00e4rkte von Kalshi in gleicher Weise verbietet, wie sie derzeit in Michigan, Nevada und im Bundesstaat Washington gesperrt sind.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a74226650\" class=\"esi-paragraph \">\n    \n<p>An anderer Stelle entschied ein Richter in Montana gegen Kalshi, was dazu f\u00fchren k\u00f6nnte, dass der Betreiber im \u201eBig Sky Country\u201c gesperrt wird. Die Esport-Weltmeisterschaft sorgt bei Kalshi f\u00fcr steigendes Handelsvolumen, doch MSI und IEM bleiben die gr\u00f6\u00dften Events<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a74226712\" class=\"esi-paragraph \">\n    \n<p>In der letzten Woche der Esport-Weltmeisterschaft wurden auf Kalshi Rekordhandelsvolumina verzeichnet. In den letzten sieben Tagen des Turniers wurden bei Esport-Events \u00fcber 95 Mio. $ umgesetzt.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a742267f3\" class=\"esi-paragraph \">\n    \n<p>Dies war ein Anstieg gegen\u00fcber den 90 Mio. $ der Vorwoche. Das Volumen lag in jeder Woche des Turniers \u2013 bis auf eine Ausnahme \u2013 \u00fcber 70 Mio. $, obwohl nicht alle Handelsaktivit\u00e4ten auf die Weltmeisterschaft entfielen.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a742268bf\" class=\"esi-paragraph \">\n    \n<p>Tats\u00e4chlich wurde letzte Woche bei \u201eLeague of Legends\u201c-Events genauso viel gehandelt wie bei CS2, obwohl Letzteres bei der Weltmeisterschaft im Rampenlicht stand. Beide Spiele verzeichneten ein Gesamtvolumen von rund 32 Mio. $.<\/p>\n\n  <\/div>\n\n\n<div id=\"esi-paragraph-6a98a7422698c\" class=\"esi-paragraph \">\n    \n<p class=\"has-cyan-bluish-gray-background-color has-background\"><strong>Hinweis:<\/strong> <em>In Deutschland stuft die Gemeinsame Gl\u00fccksspielbeh\u00f6rde der L\u00e4nder (GGL) sogenannte Gesellschaftswetten, wie sie etwa auf Polymarket angeboten werden, als nicht erlaubnisf\u00e4hig ein. Dieser Beitrag dient ausschlie\u00dflich Informationszwecken.<\/em><\/p>\n\n  <\/div>\n","protected":false},"excerpt":{"rendered":"<p>In der letzten Woche der Esport-Weltmeisterschaft wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten sieben Tagen des Turniers wurden bei Esport-Veranstaltungen insgesamt \u00fcber 95 Mio. $ umgesetzt. Dies war ein Anstieg gegen\u00fcber den 90 Mio. $ der Vorwoche. Mit einer Ausnahme lag das Handelsvolumen in jeder Woche des Turniers \u00fcber 70 Mio. $, wobei nicht &hellip; <a href=\"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\">Continued<\/a><\/p>\n","protected":false},"author":381,"featured_media":23029,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_lmt_disableupdate":"","_lmt_disable":"","esi_template":"default","excluded":false,"footnotes":""},"categories":[28,42,41],"tags":[262,282,285,283,242,284],"class_list":["post-23028","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-aktuelle-news","category-counter-strike","category-lol","tag-cs2","tag-esports-world-cup","tag-iem-koeln","tag-kalshi","tag-league-of-legends","tag-msi"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.8 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>EWC sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM gr\u00f6\u00dfte Events<\/title>\n<meta name=\"description\" content=\"In der letzten Woche der Esport-WM wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten 7 Turniertagen wurden bei Esport-Events 95 Mio. $ umgesetzt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"EWC sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM gr\u00f6\u00dfte Events\" \/>\n<meta property=\"og:description\" content=\"In der letzten Woche der Esport-WM wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten 7 Turniertagen wurden bei Esport-Events 95 Mio. $ umgesetzt.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\" \/>\n<meta property=\"og:site_name\" content=\"Esports Insider Deutsch\" \/>\n<meta property=\"article:published_time\" content=\"2026-09-01T08:30:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-09-01T08:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/MSI-2025-fans-large.jpg.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1024\" \/>\n\t<meta property=\"og:image:height\" content=\"683\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"author\" content=\"Nicole Mark\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@esportsinsider\" \/>\n<meta name=\"twitter:site\" content=\"@esportsinsider\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Nicole Mark\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"NewsArticle\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\"},\"author\":{\"name\":\"Nicole Mark\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#\\\/schema\\\/person\\\/0bfa631693cc3d831d01d93d5e688c0f\"},\"headline\":\"Esports World Cup sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM bleiben gr\u00f6\u00dfte Veranstaltungen\",\"datePublished\":\"2026-09-01T08:30:28+00:00\",\"dateModified\":\"2026-09-01T08:30:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\"},\"wordCount\":874,\"publisher\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/MSI-2025-fans-large.jpg.webp\",\"keywords\":[\"CS2\",\"Esports World Cup\",\"IEM K\u00f6ln\",\"Kalshi\",\"League of Legends\",\"MSI\"],\"articleSection\":[\"Aktuelle News\",\"Counter Strike\",\"League of Legends\"],\"inLanguage\":\"de\",\"copyrightYear\":\"2026\",\"copyrightHolder\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/#organization\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\",\"name\":\"EWC sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM gr\u00f6\u00dfte Events\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/MSI-2025-fans-large.jpg.webp\",\"datePublished\":\"2026-09-01T08:30:28+00:00\",\"dateModified\":\"2026-09-01T08:30:29+00:00\",\"description\":\"In der letzten Woche der Esport-WM wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten 7 Turniertagen wurden bei Esport-Events 95 Mio. $ umgesetzt.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/MSI-2025-fans-large.jpg.webp\",\"contentUrl\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/09\\\/MSI-2025-fans-large.jpg.webp\",\"width\":1024,\"height\":683,\"caption\":\"Liu YiCun\\\/Riot Games, MSI 2025 Fans\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/2026\\\/09\\\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aktuelle News\",\"item\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/aktuelle-news\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Esports World Cup sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM bleiben gr\u00f6\u00dfte Veranstaltungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\",\"name\":\"Esports Insider Deutsch\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#organization\",\"name\":\"Esports Insider\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/esi_logo_white.jpg\",\"contentUrl\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/esi_logo_white.jpg\",\"width\":900,\"height\":900,\"caption\":\"Esports Insider\"},\"image\":{\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/esportsinsider\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/#\\\/schema\\\/person\\\/0bfa631693cc3d831d01d93d5e688c0f\",\"name\":\"Nicole Mark\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/avatar_user_381_1758616729-96x96.jpg\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/avatar_user_381_1758616729-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/avatar_user_381_1758616729-96x96.jpg\",\"caption\":\"Nicole Mark\"},\"description\":\"Nicole arbeitet nach ihrem Studium der Germanistik, Kunst- und Filmgeschichte an der Ruprecht-Karls-Universit\u00e4t Heidelberg bereits seit 2013 als freiberufliche Content Managerin, \u00dcbersetzerin und Texterin . Zudem ist sie als Designerin und WP,- Audio- und Video-Editorin t\u00e4tig und betreut Personen des \u00f6ffentlichen Lebens als PR- und Marketing-Managerin. F\u00fcr Esportsinsider sorgt Nicole daf\u00fcr, dass unsere Guides und Artikel auch f\u00fcr deutsche Leser pr\u00e4zise, verst\u00e4ndlich und leserfreundlich sind.\",\"url\":\"https:\\\/\\\/esportsinsider.com\\\/de\\\/author\\\/nicolemark\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"EWC sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM gr\u00f6\u00dfte Events","description":"In der letzten Woche der Esport-WM wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten 7 Turniertagen wurden bei Esport-Events 95 Mio. $ umgesetzt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg","og_locale":"de_DE","og_type":"article","og_title":"EWC sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM gr\u00f6\u00dfte Events","og_description":"In der letzten Woche der Esport-WM wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten 7 Turniertagen wurden bei Esport-Events 95 Mio. $ umgesetzt.","og_url":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg","og_site_name":"Esports Insider Deutsch","article_published_time":"2026-09-01T08:30:28+00:00","article_modified_time":"2026-09-01T08:30:29+00:00","og_image":[{"width":1024,"height":683,"url":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/MSI-2025-fans-large.jpg.webp","type":"image\/webp"}],"author":"Nicole Mark","twitter_card":"summary_large_image","twitter_creator":"@esportsinsider","twitter_site":"@esportsinsider","twitter_misc":{"Written by":"Nicole Mark","Est. reading time":"6 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"NewsArticle","@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#article","isPartOf":{"@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg"},"author":{"name":"Nicole Mark","@id":"https:\/\/esportsinsider.com\/de\/#\/schema\/person\/0bfa631693cc3d831d01d93d5e688c0f"},"headline":"Esports World Cup sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM bleiben gr\u00f6\u00dfte Veranstaltungen","datePublished":"2026-09-01T08:30:28+00:00","dateModified":"2026-09-01T08:30:29+00:00","mainEntityOfPage":{"@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg"},"wordCount":874,"publisher":{"@id":"https:\/\/esportsinsider.com\/de\/#organization"},"image":{"@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage"},"thumbnailUrl":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/MSI-2025-fans-large.jpg.webp","keywords":["CS2","Esports World Cup","IEM K\u00f6ln","Kalshi","League of Legends","MSI"],"articleSection":["Aktuelle News","Counter Strike","League of Legends"],"inLanguage":"de","copyrightYear":"2026","copyrightHolder":{"@id":"https:\/\/esportsinsider.com\/#organization"}},{"@type":"WebPage","@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg","url":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg","name":"EWC sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM gr\u00f6\u00dfte Events","isPartOf":{"@id":"https:\/\/esportsinsider.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage"},"image":{"@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage"},"thumbnailUrl":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/MSI-2025-fans-large.jpg.webp","datePublished":"2026-09-01T08:30:28+00:00","dateModified":"2026-09-01T08:30:29+00:00","description":"In der letzten Woche der Esport-WM wurden auf Kalshi Rekordums\u00e4tze verzeichnet. In den letzten 7 Turniertagen wurden bei Esport-Events 95 Mio. $ umgesetzt.","breadcrumb":{"@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#primaryimage","url":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/MSI-2025-fans-large.jpg.webp","contentUrl":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2026\/09\/MSI-2025-fans-large.jpg.webp","width":1024,"height":683,"caption":"Liu YiCun\/Riot Games, MSI 2025 Fans"},{"@type":"BreadcrumbList","@id":"https:\/\/esportsinsider.com\/de\/2026\/09\/esports-world-cup-sorgt-bei-kalshi-fuer-umsatzanstieg#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/esportsinsider.com\/de\/"},{"@type":"ListItem","position":2,"name":"Aktuelle News","item":"https:\/\/esportsinsider.com\/de\/aktuelle-news"},{"@type":"ListItem","position":3,"name":"Esports World Cup sorgt bei Kalshi f\u00fcr Umsatzanstieg, MSI und IEM bleiben gr\u00f6\u00dfte Veranstaltungen"}]},{"@type":"WebSite","@id":"https:\/\/esportsinsider.com\/de\/#website","url":"https:\/\/esportsinsider.com\/de","name":"Esports Insider Deutsch","description":"","publisher":{"@id":"https:\/\/esportsinsider.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/esportsinsider.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/esportsinsider.com\/de\/#organization","name":"Esports Insider","url":"https:\/\/esportsinsider.com\/de","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/esportsinsider.com\/de\/#\/schema\/logo\/image","url":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/esi_logo_white.jpg","contentUrl":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/esi_logo_white.jpg","width":900,"height":900,"caption":"Esports Insider"},"image":{"@id":"https:\/\/esportsinsider.com\/de\/#\/schema\/logo\/image"},"sameAs":["https:\/\/x.com\/esportsinsider"]},{"@type":"Person","@id":"https:\/\/esportsinsider.com\/de\/#\/schema\/person\/0bfa631693cc3d831d01d93d5e688c0f","name":"Nicole Mark","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/avatar_user_381_1758616729-96x96.jpg","url":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/avatar_user_381_1758616729-96x96.jpg","contentUrl":"https:\/\/esportsinsider.com\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/avatar_user_381_1758616729-96x96.jpg","caption":"Nicole Mark"},"description":"Nicole arbeitet nach ihrem Studium der Germanistik, Kunst- und Filmgeschichte an der Ruprecht-Karls-Universit\u00e4t Heidelberg bereits seit 2013 als freiberufliche Content Managerin, \u00dcbersetzerin und Texterin . Zudem ist sie als Designerin und WP,- Audio- und Video-Editorin t\u00e4tig und betreut Personen des \u00f6ffentlichen Lebens als PR- und Marketing-Managerin. F\u00fcr Esportsinsider sorgt Nicole daf\u00fcr, dass unsere Guides und Artikel auch f\u00fcr deutsche Leser pr\u00e4zise, verst\u00e4ndlich und leserfreundlich sind.","url":"https:\/\/esportsinsider.com\/de\/author\/nicolemark"}]}},"modified_by":"Nicole Mark","_links":{"self":[{"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/posts\/23028","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/users\/381"}],"replies":[{"embeddable":true,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/comments?post=23028"}],"version-history":[{"count":1,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/posts\/23028\/revisions"}],"predecessor-version":[{"id":23033,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/posts\/23028\/revisions\/23033"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/media\/23029"}],"wp:attachment":[{"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/media?parent=23028"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/categories?post=23028"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/esportsinsider.com\/de\/wp-json\/wp\/v2\/tags?post=23028"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}